{"id":60,"count":1,"description":"","link":"https:\/\/hurt-tanio.pl\/en\/tag\/okulary-przeciwsloneczne-lato\/","name":"okulary przeciws\u0142oneczne lato","slug":"okulary-przeciwsloneczne-lato","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>okulary przeciws\u0142oneczne lato - Hurt Tanio \u2013 Hurtownia Okular\u00f3w<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hurt-tanio.pl\/en\/tag\/okulary-przeciwsloneczne-lato\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"okulary przeciws\u0142oneczne lato - Hurt Tanio \u2013 Hurtownia Okular\u00f3w\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hurt-tanio.pl\/en\/tag\/okulary-przeciwsloneczne-lato\/\" \/>\n<meta property=\"og:site_name\" content=\"Hurt Tanio \u2013 Hurtownia Okular\u00f3w\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hurt-tanio.pl\\\/tag\\\/okulary-przeciwsloneczne-lato\\\/\",\"url\":\"https:\\\/\\\/hurt-tanio.pl\\\/tag\\\/okulary-przeciwsloneczne-lato\\\/\",\"name\":\"okulary przeciws\u0142oneczne lato - Hurt Tanio \u2013 Hurtownia Okular\u00f3w\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hurt-tanio.pl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hurt-tanio.pl\\\/tag\\\/okulary-przeciwsloneczne-lato\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hurt-tanio.pl\\\/tag\\\/okulary-przeciwsloneczne-lato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/hurt-tanio.pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"okulary przeciws\u0142oneczne lato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hurt-tanio.pl\\\/#website\",\"url\":\"https:\\\/\\\/hurt-tanio.pl\\\/\",\"name\":\"Hurt Tanio \u2013 Hurtownia Okular\u00f3w\",\"description\":\"Atrakcyjne ceny, modele kt\u00f3re si\u0119 sprzedaj\u0105\",\"publisher\":{\"@id\":\"https:\\\/\\\/hurt-tanio.pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hurt-tanio.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hurt-tanio.pl\\\/#organization\",\"name\":\"Hurt Tanio \u2013 Hurtownia Okular\u00f3w\",\"url\":\"https:\\\/\\\/hurt-tanio.pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/hurt-tanio.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hurt-tanio.pl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-Tani-hurt-okularow.png\",\"contentUrl\":\"https:\\\/\\\/hurt-tanio.pl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-Tani-hurt-okularow.png\",\"width\":915,\"height\":228,\"caption\":\"Hurt Tanio \u2013 Hurtownia Okular\u00f3w\"},\"image\":{\"@id\":\"https:\\\/\\\/hurt-tanio.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"okulary przeciws\u0142oneczne lato - Hurt Tanio \u2013 Hurtownia Okular\u00f3w","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hurt-tanio.pl\/en\/tag\/okulary-przeciwsloneczne-lato\/","og_locale":"en_GB","og_type":"article","og_title":"okulary przeciws\u0142oneczne lato - Hurt Tanio \u2013 Hurtownia Okular\u00f3w","og_url":"https:\/\/hurt-tanio.pl\/en\/tag\/okulary-przeciwsloneczne-lato\/","og_site_name":"Hurt Tanio \u2013 Hurtownia Okular\u00f3w","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hurt-tanio.pl\/tag\/okulary-przeciwsloneczne-lato\/","url":"https:\/\/hurt-tanio.pl\/tag\/okulary-przeciwsloneczne-lato\/","name":"okulary przeciws\u0142oneczne lato - Hurt Tanio \u2013 Hurtownia Okular\u00f3w","isPartOf":{"@id":"https:\/\/hurt-tanio.pl\/#website"},"breadcrumb":{"@id":"https:\/\/hurt-tanio.pl\/tag\/okulary-przeciwsloneczne-lato\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/hurt-tanio.pl\/tag\/okulary-przeciwsloneczne-lato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/hurt-tanio.pl\/"},{"@type":"ListItem","position":2,"name":"okulary przeciws\u0142oneczne lato"}]},{"@type":"WebSite","@id":"https:\/\/hurt-tanio.pl\/#website","url":"https:\/\/hurt-tanio.pl\/","name":"Hurt Tanio \u2013 Hurtownia Okular\u00f3w","description":"Atrakcyjne ceny, modele kt\u00f3re si\u0119 sprzedaj\u0105","publisher":{"@id":"https:\/\/hurt-tanio.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hurt-tanio.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/hurt-tanio.pl\/#organization","name":"Hurt Tanio \u2013 Hurtownia Okular\u00f3w","url":"https:\/\/hurt-tanio.pl\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/hurt-tanio.pl\/#\/schema\/logo\/image\/","url":"https:\/\/hurt-tanio.pl\/wp-content\/uploads\/2026\/05\/cropped-Tani-hurt-okularow.png","contentUrl":"https:\/\/hurt-tanio.pl\/wp-content\/uploads\/2026\/05\/cropped-Tani-hurt-okularow.png","width":915,"height":228,"caption":"Hurt Tanio \u2013 Hurtownia Okular\u00f3w"},"image":{"@id":"https:\/\/hurt-tanio.pl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hurt-tanio.pl\/en\/wp-json\/wp\/v2\/tags\/60","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hurt-tanio.pl\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hurt-tanio.pl\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hurt-tanio.pl\/en\/wp-json\/wp\/v2\/posts?tags=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}